{"id":17191,"date":"2022-05-06T19:14:48","date_gmt":"2022-05-06T22:14:48","guid":{"rendered":"https:\/\/euvivoaselecao.com.br\/?p=17191"},"modified":"2022-05-06T19:14:48","modified_gmt":"2022-05-06T22:14:48","slug":"vasco-so-venceu-2-dos-ultimos-10-jogos-contra-o-csa-veja-retrospecto-vasconet","status":"publish","type":"post","link":"https:\/\/euvivoaselecao.com.br\/index.php\/2022\/05\/06\/vasco-so-venceu-2-dos-ultimos-10-jogos-contra-o-csa-veja-retrospecto-vasconet\/","title":{"rendered":"Vasco s\u00f3 venceu 2 dos \u00faltimos 10 jogos contra o CSA; veja retrospecto &#8211; VASCONet"},"content":{"rendered":"<p> <a href=\"https:\/\/news.google.com\/publications\/CAAqBwgKMMvIlgswru6tAw?hl=pt-BR&amp;gl=BR&amp;ceid=BR%3Apt-419\"><strong>SIGA-NOS<\/strong>  <\/a>            <\/p>\n<p>Vasco s\u00f3 venceu 2 dos \u00faltimos 10 jogos contra o CSA; veja retrospecto Sexta-feira, 06\/05\/2022 &#8211; 18:52 O CSA tem se dado bem contra o Vasco no hist\u00f3rico recente. Nos \u00faltimos dez jogos oficiais, venceu tr\u00eas, empatou cinco e perdeu dois. Neste s\u00e1bado, os times se enfrentam \u00e0s 19h, em S\u00e3o Janu\u00e1rio, pela sexta rodada da S\u00e9rie B. <\/p>\n<p>Ano passado, por exemplo, o CSA empatou por 2 a 2, no Rei Pel\u00e9, e venceu em S\u00e3o Janu\u00e1rio por 3 a 1. As duas partidas foram disputadas pela S\u00e9rie B. <\/p>\n<p>Deu tanto trabalho que o Vasco foi buscar dois de seus destaques no final da temporada: o goleiro Thiago Rodrigues e o volante Yuri Lara. <\/p>\n<p>Neste ano, no entanto, o CSA conta com um zagueiro que atuou pelo Vasco por um longo per\u00edodo. Werley \u00e9 titular da equipe alagoana e forma dupla com Luc\u00e3o. O lateral-esquerdo Diego Renan tamb\u00e9m j\u00e1 defendeu o time carioca. <\/p>\n<p>Que vit\u00f3ria! <\/p>\n<p>Historicamente, o CSA tamb\u00e9m tem um feito contra o Vasco: eliminou o time carioca na Copa do Brasil de 1992, com um gol de Dago, em S\u00e3o Janu\u00e1rio. No primeiro jogo do mata-mata, os times empataram por 3 a 3 no Est\u00e1dio da Paju\u00e7ara, em Macei\u00f3. <\/p>\n<p>E neste ano? <\/p>\n<p>Neste s\u00e1bado, no entanto, o CSA precisa melhorar seu desempenho como visitante na S\u00e9rie B. Em dois jogos at\u00e9 agora fora de casa, foi batido uma vez, pelo Brusque, por 2 a 0, e empatou sem gols com o Ituano. <\/p>\n<p>O ataque ainda n\u00e3o balan\u00e7ou a rede como visitante. Por outro lado, o Vasco ainda n\u00e3o perdeu como mandante nesta S\u00e9rie B. Empatou um jogo e venceu outro. <\/p>\n<p>\u00daltimos confrontos <\/p>\n<p>&gt; Brasileiro 1981 -CSA 1 x 1 Vasco &gt; Brasileiro 1981- Vasco 1 x 1 CSA &gt; Copa do Brasil 1992 &#8211; CSA 3 x 3 Vasco &gt; Copa do Brasil 1992 &#8211; Vasco 0 x 1 CSA &gt; Copa do Brasil 2002 &#8211; CSA 2 x 1 Vasco &gt; Copa do Brasil 2002 &#8211; Vasco 4 x 0 CSA &gt; Brasileiro 2019 &#8211; CSA 0 x 3 Vasco &gt; Brasileiro 2019 &#8211; Vasco 0 x 0 CSA &gt; S\u00e9rie B 2021 &#8211; CSA 2 x 2 Vasco &gt; S\u00e9rie B 2021 &#8211; Vasco 1 x 3 CSA <\/p>\n<p><a href=\"\/news\/noticias16\/arquivos\/20220506-172415-1-csa-venceu-o-vasco-no-ano-passado-em-sao-januario.jpg\" title=\"CSA venceu o Vasco no ano passado, em S\u00e3o Janu\u00e1rio\" class=\"thickbox fancybox\" rel=\"ligthbox\">CSA venceu o Vasco no ano passado, em S\u00e3o Janu\u00e1rio<\/a> <\/p>\n<p>Fonte: ge<\/p>\n<h3 class=\"sd-title\">Compartilhe<\/h3>\n<h3 class=\"sd-title\">Like this:<\/h3>\n<p>Like Loading&#8230;<a class='sd-link-color'><\/a>  <\/p>\n<h3 class=\"jp-relatedposts-headline\">Relacionado<\/h3>\n<p>Fonte: <a href=\"\/\/vasconet.com.br\/2022\/05\/06\/vasco-so-venceu-2-dos-ultimos-10-jogos-contra-o-csa-veja-retrospecto\" title=\"vasconet.com.br\/2022\/05\/06\/vasco-so-venceu-2-dos-ultimos-10-jogos-contra-o-csa-veja-retrospecto\" target=\"_blank\" rel=\"bookmark noopener\"><cite>vasconet.com.br\/2022\/05\/06\/vasco-so-venceu-2-dos-ultimos-10-jogos-contra-o-csa-veja-retrospecto<\/cite><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SIGA-NOS Vasco s\u00f3 venceu 2 dos \u00faltimos 10 jogos contra o CSA; veja retrospecto Sexta-feira, 06\/05\/2022 &#8211; 18:52 O CSA<\/p>\n","protected":false},"author":1,"featured_media":17192,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","footnotes":""},"categories":[15],"tags":[],"class_list":["post-17191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17191"}],"version-history":[{"count":1,"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17191\/revisions"}],"predecessor-version":[{"id":17193,"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17191\/revisions\/17193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/media\/17192"}],"wp:attachment":[{"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/euvivoaselecao.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}